{"id":11,"date":"2006-05-24T08:15:32","date_gmt":"2006-05-24T06:15:32","guid":{"rendered":"http:\/\/ru3.com\/luc\/?p=11"},"modified":"2006-05-24T08:15:32","modified_gmt":"2006-05-24T06:15:32","slug":"trentieme-carrefour-des-possibles-de-la-fing","status":"publish","type":"post","link":"https:\/\/ru3.com\/luc\/tag\/meeting\/trentieme-carrefour-des-possibles-de-la-fing.html","title":{"rendered":"Trenti\u00e8me carrefour des possibles de la Fing"},"content":{"rendered":"<p><span style=\"font-weight: bold;\">Hier, mardi 23 mai, avait lieu au <a href=\"http:\/\/www.education.gouv.fr\/\">minist\u00e8re de l&rsquo;\u00e9ducation et de la Recherche<\/a> le 30e carrefour des possibles de la  <a href=\"http:\/\/www.fing.fr\/\">Fing<\/a>.<\/span><\/p>\n<p>Une nouvelle occasion de parler hier soir avec : <span style=\"font-weight: bold;\">Christian Brugeron<\/span>, directeur associ\u00e9 de <a href=\"http:\/\/newsme.org\">NewsMe<\/a>, <span style=\"font-weight: bold;\">Antoine Dulaure<\/span>, charg\u00e9 de mission au centre Georges Pompidou (<a href=\"http:\/\/ru3.com\/luc\/2006\/03\/le-centre-pompidou-lance-un-institut.html\">voir sa pr\u00e9sentation<\/a>), <span style=\"font-weight: bold;\">Pierre Bernard<\/span>, blogtrotter (<a href=\"http:\/\/ze6tmd.kd2.org\/\">ze6tmd<\/a>), <span style=\"font-weight: bold;\">Jean-Fran\u00e7ois Dubos<\/span>, consultant en ergonomie (<a href=\"http:\/\/www.ergonomica.fr\">Ergonomica<\/a>), et <span style=\"font-weight: bold;\">Christian Hesse<\/span>, (<a href=\"http:\/\/www.visiware.com\/\">Visiware<\/a>).<br \/>\nTrop rapidement crois\u00e9s : <span style=\"font-weight: bold;\">Denis Pansu<\/span> (<a href=\"http:\/\/fing.org\">Fing<\/a>), <span style=\"font-weight: bold;\">Hubert Guillaud<\/span> (<a href=\"http:\/\/leromanais.free.fr\/\">LeRomanais<\/a>), <span style=\"font-weight: bold;\">Olivier S\u00e9r\u00e8s<\/span> (<a href=\"http:\/\/www.bouyguestelecom.fr\/\">Bouygues T\u00e9l\u00e9com<\/a>) et <span style=\"font-weight: bold;\">Yann Mauchamp<\/span> (<a href=\"http:\/\/www.openbc.com\/\">OpenBC<\/a>).<br \/>\nEt aper\u00e7u de loin : <span style=\"font-weight: bold;\">Olivier Aubert<\/span> (<a href=\"http:\/\/anoptique.com\/\">Anoptique<\/a>), <span style=\"font-weight: bold;\">Cyril Fievet<\/span> (<a href=\"http:\/\/www.nanoblog.com\/\">Nanoblog<\/a>), <span style=\"font-weight: bold;\">St\u00e9phane Lee<\/span> (<a href=\"http:\/\/stephane.etsoncar.net\/\">Endeavour<\/a>).<\/p>\n<p>Les dix projets qui ont \u00e9t\u00e9 pr\u00e9sent\u00e9s hier soir au 30e carrefour des possibles.<br \/>\n<span style=\"font-weight: bold;\"><br \/>\n1. EZ access<\/span><\/p>\n<blockquote><p>\u00ab\u00a097% des sites web ne sont pas accessibles\u00a0\u00bb. <\/p><\/blockquote>\n<p>&#8230; Et ne r\u00e9pondent donc pas aux normes d&rsquo;accessibilit\u00e9 recommand\u00e9es par le W3C !<br \/>\nA propos d&rsquo;accessibilit\u00e9, Herv\u00e9 Bloch, directeur associ\u00e9 chez <a href=\"http:\/\/www.nexint.fr\/nexint\/\">Nexint<\/a>, pr\u00e9cise que \u00ab outre son action b\u00e9n\u00e9fique pour favoriser l?acc\u00e8s \u00e0 Internet des personnes handicap\u00e9es, l?accessibilit\u00e9 optimise le r\u00e9f\u00e9rencement naturel des sites sur les moteurs de recherche, la compatibilit\u00e9 avec tous les navigateurs Internet et l?interop\u00e9rabilit\u00e9 avec les terminaux mobiles et embarqu\u00e9s \u00bb<br \/>\nEZ access, permet de rendre automatiquement accessible un site existant !<br \/>\nSite : <a href=\"http:\/\/www.nexint.fr\/nexint\/index.php?content=ezaccess\">EzAccess<\/a><br \/>\n<span style=\"font-weight: bold;\"><br \/>\n2. Dotem AlpahCode<\/span><br \/>\nUn AlphaCode est fond\u00e9 sur un concept innovant de repr\u00e9sentation de l&rsquo;information, en rupture avec la logique des autres Codes 2D. En effet, un Alphacode est une police de caract\u00e8res, alors que les Codes 2D existants se pr\u00e9sentent sous forme d&rsquo;image. Lisible avec un t\u00e9l\u00e9phone portable muni d&rsquo;un appareil photo.<br \/>\nContact : Christian Martin<br \/>\nSite : <a href=\"http:\/\/www.alphacode.eu\/\">http:\/\/www.alphacode.eu\/<\/a><br \/>\nCommuniqu\u00e9 de presse : <a href=\"http:\/\/www.conferencevirtuelle.com\/CommuniquePresse.asp?id=4395\">Dotem<\/a><\/p>\n<p><span style=\"font-weight: bold;\">3. Spark Angels<\/span><br \/>\n\u00ab\u00a0L&rsquo;internet t\u00e9l\u00e9-accompagn\u00e9\u00a0\u00bb<br \/>\nPr\u00e9sent\u00e9 par Franck Rougeau, le service propos\u00e9 permet d&rsquo;assister \u00e0 distance les utilisateurs d&rsquo;internet \u00e0 travers une plate-forme d&rsquo;\u00e9change de services. L&rsquo;ambition de SparkAngels est d&rsquo;\u00e9tendre le p\u00e9rim\u00e8tre de l&rsquo;accompagnement au del\u00e0 du cercle des proches \u00e0 travers un v\u00e9ritable service de coaching num\u00e9rique communautaire.<br \/>\n<span style=\"font-weight: bold;\"><br \/>\n4. BlueKiwi<\/span><\/p>\n<blockquote><p>\u00ab\u00a0Pour des conversation fructueuses\u00a0\u00bb<\/p><\/blockquote>\n<p>G\u00e9n\u00e9rateur et gestionnaire de blogs sur le r\u00e9seau intranet d&rsquo;une entreprise. Le syst\u00e8me comprend un portail d&rsquo;agr\u00e9gation des blogs publi\u00e9s. Une solution d\u00e9j\u00e0 adopt\u00e9e par quelques grands comptes, notamment Dassault Syst\u00e8mes.<br \/>\nSite : <a href=\"http:\/\/www.groupereflect.net\/blueKiwi\/index.html\">blueKiwi<\/a><\/p>\n<p><span style=\"font-weight: bold;\">5. MySmartBoard<\/span><br \/>\nUn tableau blanc graphique partag\u00e9 qui permet d&rsquo;\u00e9diter et de publier du contenu graphique sur son site web ou d&rsquo;exporter son contenu vers diff\u00e9rents format graphiques.<br \/>\nLes documents produits peuvent \u00eatre affich\u00e9s sur des t\u00e9l\u00e9phones\/PDA compatibles SVG. Un produit de Grynamic. Contact : Fran\u00e7oise Herbreteau.<br \/>\nSite : <a href=\"http:\/\/www.mysmartboard.com\/\">http:\/\/www.mysmartboard.com\/<\/a><br \/>\n<span style=\"font-weight: bold;\"><br \/>\n6. Wikio<\/span><br \/>\nL&rsquo;agr\u00e9gateur d&rsquo;information de <a href=\"http:\/\/kelblog.typepad.com\/\">Pierre Chappaz<\/a> (ex-Kelkoo.fr) revendique d\u00e9j\u00e0 20.000 beta testeurs. Ouverture pr\u00e9vue en juin.<br \/>\nSite : <a href=\"http:\/\/www.wikio.fr\/\">wikio.fr<\/a><\/p>\n<p><span style=\"font-weight: bold;\">7. Jurispedia.org<\/span><br \/>\nBas\u00e9 sur un wiki, JurisPedia est un projet encyclop\u00e9dique d&rsquo;initiative universitaire ouvert \u00e0 tous et consacr\u00e9 aux droits du monde et aux sciences juridiques et politiques. Le wiki couvre les textes de l\u00e9gislation de 30 pays.<br \/>\nActif depuis 18 mois, 1400 articles en langue fran\u00e7aise et 1700 en langue arabe.<br \/>\nContact : Hughes-Jehan Vibert.<br \/>\nSite : <a href=\"http:\/\/jurispedia.org\">jurispedia.org<\/a><\/p>\n<p><span style=\"font-weight: bold;\">8. Viviane<\/span><\/p>\n<blockquote><p>\u00ab\u00a0Agissez pour comprendre et pr\u00e9servez notre environnement\u00a0\u00bb<\/p><\/blockquote>\n<p>Outil d&rsquo;apprentissage grand public utilisant une interface riche 3D permettant de sensibiliser les citoyens \u00e0 la gestion de l&rsquo;environnement.<br \/>\nSite : <a href=\"http:\/\/viviane.c3ed.uvsq.fr\/\">http:\/\/viviane.c3ed.uvsq.fr\/<\/a><\/p>\n<p><span style=\"font-weight: bold;\">9. K-motion <\/span><br \/>\nPr\u00e9sent\u00e9 par Clothilde Huet et C\u00e9cile Baltazart de l&rsquo;\u00e9cole <a href=\"http:\/\/www.ensad.fr\/accueil.htm\">Ensad<\/a>. Acc\u00e8s \u00e0 un r\u00e9seau mobile d&rsquo;\u00e9change musical et \u00e9motionnel. Pour \u00e9couter et partager en temps r\u00e9el sa playlist mp3 avec son entourage imm\u00e9diat.<br \/>\n<span style=\"font-weight: bold;\"><br \/>\n10. Peau m\u00e9moire<\/span><br \/>\nSyst\u00e8me et interfaces tactiles pour spectacles chor\u00e9graphiques permettant aux danseurs de contr\u00f4ler leur environnement sonore et musical.<br \/>\nSite : <a href=\"http:\/\/www.sylvielequere.com\/\">http:\/\/www.sylvielequere.com\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier, mardi 23 mai, avait lieu au minist\u00e8re de l&rsquo;\u00e9ducation et de la Recherche le 30e carrefour des possibles de la Fing. Une nouvelle occasion de parler hier soir avec : Christian Brugeron, directeur associ\u00e9 de NewsMe, Antoine Dulaure, charg\u00e9 de mission au centre Georges Pompidou (voir sa pr\u00e9sentation), Pierre Bernard, blogtrotter (ze6tmd), Jean-Fran\u00e7ois Dubos, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/ru3.com\/luc\/tag\/meeting\/trentieme-carrefour-des-possibles-de-la-fing.html\" class=\"more-link\">Continuer la lecture <span class=\"screen-reader-text\"> \u00ab\u00a0Trenti\u00e8me carrefour des possibles de la Fing\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,19,18,11],"tags":[],"class_list":["post-11","post","type-post","status-publish","format-standard","hentry","category-meeting","category-evenement","category-fing","category-people","entry"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/posts\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":0,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/posts\/11\/revisions"}],"wp:attachment":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/media?parent=11"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/categories?post=11"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/tags?post=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}