{"id":23,"date":"2006-06-13T08:55:11","date_gmt":"2006-06-13T06:55:11","guid":{"rendered":"http:\/\/ru3.com\/luc\/?p=23"},"modified":"2006-11-13T13:02:28","modified_gmt":"2006-11-13T11:02:28","slug":"linfluence-de-la-blogosphere-sur-les-medias-et-sur-la-societe","status":"publish","type":"post","link":"https:\/\/ru3.com\/luc\/tag\/collective-intelligence\/linfluence-de-la-blogosphere-sur-les-medias-et-sur-la-societe.html","title":{"rendered":"L&rsquo;influence de la blogosph\u00e8re sur les m\u00e9dias et sur la soci\u00e9t\u00e9"},"content":{"rendered":"<p><span style=\"font-weight: bold;\">Un extrait de l&rsquo;intervention de <a href=\"http:\/\/pisani.blog.lemonde.fr\/pisani\/\">Francis Pisani<\/a>, par vid\u00e9o conf\u00e9rence interpos\u00e9e, lors de l&rsquo;Universit\u00e9 de printemps de la Fing d&rsquo;Aix-en-Provence.<\/span><\/p>\n<div style=\"margin-bottom:25px;margin-top:25px;\">\n<div style=\"width:320px;text-align:left;\">\n<style type=\"text\/css\"><!-- #iz7ngfmeewo8vadymy5s5auwdm10ul5d5ag2q7vfa{width:320px;height:256px;border:none;margin:0px;} --><\/style>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.dailymotion.com\/blog\/video\/252172?key=z7ngfmeewo8vadymy5s5auwdm10ul5d5ag2q7vfa\" style=\"width:320px;height:256px;border:none;margin:0px;\" width=\"320\" height=\"256\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" id=\"iz7ngfmeewo8vadymy5s5auwdm10ul5d5ag2q7vfa\">Dailymotion blogged video<\/iframe><br \/><span style=\"margin-top:0px;\"><a href=\"http:\/\/www.dailymotion.com\/video\/252172\">Francis Pisani en vid\u00e9o conf\u00e9rence<\/a><br \/>Vid\u00e9o envoy\u00e9e par <a href=\"http:\/\/www.dailymotion.com\/lucos\">lucos<\/a><br \/><\/span><\/div>\n<\/div>\n<p>Francis Pisani, journaliste et bloggeur (<a href=\"http:\/\/pisani.blog.lemonde.fr\/pisani\/\">Transnet<\/a>) fran\u00e7ais vivant en Californie depuis 1996, est un observateur et un d\u00e9crypteur influent de la transformation du paysage m\u00e9diatique et technologique.<br \/>\nP\u00e9dagogue redoutablement efficace, puisqu&rsquo;en une minute et trente seconde nous y apprenons trois concepts-cl\u00e9s de l&rsquo;internet participatif :<\/p>\n<ul>\n<li>Avec les blogs tout le monde voit son r\u00f4le changer.<\/li>\n<li>Les journalistes ne peuvent plus faire [ou dire] de b\u00eatises.<\/li>\n<li>Les blogs sont des filtres.<\/li>\n<\/ul>\n<p>Et de conclure qu&rsquo;avec le recentrage sur l&rsquo;utilisateur, l&rsquo;internet participatif va bien au-del\u00e0 de la notion r\u00e9ductrice de journalisme citoyen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un extrait de l&rsquo;intervention de Francis Pisani, par vid\u00e9o conf\u00e9rence interpos\u00e9e, lors de l&rsquo;Universit\u00e9 de printemps de la Fing d&rsquo;Aix-en-Provence. Dailymotion blogged videoFrancis Pisani en vid\u00e9o conf\u00e9renceVid\u00e9o envoy\u00e9e par lucos Francis Pisani, journaliste et bloggeur (Transnet) fran\u00e7ais vivant en Californie depuis 1996, est un observateur et un d\u00e9crypteur influent de la transformation du paysage m\u00e9diatique &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/ru3.com\/luc\/tag\/collective-intelligence\/linfluence-de-la-blogosphere-sur-les-medias-et-sur-la-societe.html\" class=\"more-link\">Continuer la lecture <span class=\"screen-reader-text\"> \u00ab\u00a0L&rsquo;influence de la blogosph\u00e8re sur les m\u00e9dias et sur la soci\u00e9t\u00e9\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7,8,10,27,28,58,18,1,11],"tags":[],"class_list":["post-23","post","type-post","status-publish","format-standard","hentry","category-web-20-web2","category-medias","category-meeting","category-blogosphere","category-citoyennete","category-communautes","category-fing","category-collective-intelligence","category-people","entry"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/posts\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/comments?post=23"}],"version-history":[{"count":0,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/posts\/23\/revisions"}],"wp:attachment":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/media?parent=23"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/categories?post=23"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/tags?post=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}