{"id":345,"date":"2009-06-17T06:09:38","date_gmt":"2009-06-17T04:09:38","guid":{"rendered":"http:\/\/ru3.com\/luc\/?p=345"},"modified":"2009-06-17T06:19:24","modified_gmt":"2009-06-17T04:19:24","slug":"universite-ete-medias-et-communication-casablanca","status":"publish","type":"post","link":"https:\/\/ru3.com\/luc\/tag\/luc-legay\/universite-ete-medias-et-communication-casablanca.html","title":{"rendered":"\u00ab Ecrire dans tous ces m\u00e9dias\u00a0\u00bb : th\u00e8me de la troisi\u00e8me Universit\u00e9 d&rsquo;\u00e9t\u00e9 des m\u00e9dias et de la communication \u00e0 Casablanca"},"content":{"rendered":"<p><figure style=\"width: 500px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.flickr.com\/photos\/rytc\/3183822501\/\"><img loading=\"lazy\" decoding=\"async\" alt=\"Fontaine de la grande mosqu\u00e9e de Casablanca\" src=\"http:\/\/farm4.static.flickr.com\/3303\/3183822501_764dda7558.jpg\" title=\"Fontaine de la grande mosqu\u00e9e de Casablanca\" width=\"500\" height=\"375\" \/><\/a><figcaption class=\"wp-caption-text\">Fontaine de la grande mosqu\u00e9e de Casablanca. <small>By Rytc<\/small><\/figcaption><\/figure><strong>Dans le cadre de l&rsquo;Universit\u00e9, organis\u00e9e sous la direction de Paul Daudin Clavaud, douze ateliers et master class, d&rsquo;un \u00e0 deux jours chacun, sont propose?s gratuitement aux professionnels des me?dias marocains \u00e0 partir de lundi prochain, 22 juin 2009.<\/strong><\/p>\n<p>J&rsquo;y animerai les deux master class suivantes : \u00ab\u00a0<strong>Ecrire pour Internet<\/strong>\u00a0\u00bb et \u00ab\u00a0<strong>Cr\u00e9er et animer un blog professionnel<\/strong>\u00ab\u00a0.<\/p>\n<p>Dix autres ateliers et master class seront anim\u00e9s par : <strong>Joan Sauers<\/strong>, e?crivain et sce?nariste, <strong>Paul Biondi<\/strong>, journaliste a? Radio France,<strong> Luc Dubos<\/strong>, directeur artistique, <strong>Christophe Forcari<\/strong>, journaliste, <strong>Ilham Loulidi<\/strong>, enseignante spe?cialiste de la voix au Conservatoire National d\u0092Art Dramatique, <strong>Philippe Bernard<\/strong>, sce?nariste, <strong>Jean-Christophe Raczy<\/strong>, journaliste reporter d\u0092image<\/p>\n<p><em>Mon programme en quelques lignes :<\/em><br \/>\n<strong>Ecrire pour Internet <\/strong>(2 jours) : Particularite?s et originalite?s du Web. Les contraintes. Conception et e?criture (clarte? du message et du langage). Structure du contenu web. Les principes de navigation. Les pages d\u0092accueil. Les pages de navigation interme?diaires. Chartre graphique et mise en page. Le re?fe?rencement. Le ro?le du webmaster. Mises a? jour et actualisation.  <\/p>\n<p><strong>Cr\u00e9er et animer un blog professionnel<\/strong> (2 jours) : De?finitions, historique et typologie. Les usages. Les caracte?ristiques d\u0092un blog (commentaires, pingback\/trackback, flux RSS&#8230;). La syndication et l\u0092agre?gation de contenu. Les solutions d\u0092he?bergement, les plates-formes gratuites, payantes, les logiciels serveur, les solutions open source. Ouverture d\u0092un compte blog sur une plate-forme en ligne d\u00e9di\u00e9e \u00e0 l&rsquo;Universit\u00e9 d&rsquo;\u00e9t\u00e9. Parame?trage et design graphique du blog. R\u00e9daction des premiers billets. Les re?gles de publication et de style. Gestion de l\u0092image, de la vide?o et de l&rsquo;interactivit\u00e9.<\/p>\n<p>L\u0092Universite? d\u0092e?te? a rec?u cette anne?e le soutien financier de la De?le?gation de l\u0092Union Europe?enne au Maroc. <\/p>\n<p><strong>Annonces de l&rsquo;\u00e9v\u00e9nement :<\/strong><\/p>\n<ul>\n<li>\n<a href=\"http:\/\/www.esjc.ma\/index.php\/dernieres-news\/universite-d-ete-de-l-esjc.html\">ESJC Ecole sup\u00e9rieure de journalisme et de communication de Casablanca<\/a><\/li>\n<li><a href=\"http:\/\/www.efmmtc.com\/page_14.html\">Medias training Center<\/a><\/li>\n<li><a href=\"http:\/\/www.arabpressnetwork.org\/articlesv2.php?id=2305&#038;lang=fr\">Arab press network<\/a><\/li>\n<\/ul>\n<p><strong>Programme et inscription<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/ru3.com\/luc\/wp-content\/upload\/Programme-Universite-Casablanca-2009.pdf\">PDF (876 Ko)<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de l&rsquo;Universit\u00e9, organis\u00e9e sous la direction de Paul Daudin Clavaud, douze ateliers et master class, d&rsquo;un \u00e0 deux jours chacun, sont propose?s gratuitement aux professionnels des me?dias marocains \u00e0 partir de lundi prochain, 22 juin 2009. J&rsquo;y animerai les deux master class suivantes : \u00ab\u00a0Ecrire pour Internet\u00a0\u00bb et \u00ab\u00a0Cr\u00e9er et animer un &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/ru3.com\/luc\/tag\/luc-legay\/universite-ete-medias-et-communication-casablanca.html\" class=\"more-link\">Continuer la lecture <span class=\"screen-reader-text\"> \u00ab\u00a0\u00ab Ecrire dans tous ces m\u00e9dias\u00a0\u00bb : th\u00e8me de la troisi\u00e8me Universit\u00e9 d&rsquo;\u00e9t\u00e9 des m\u00e9dias et de la communication \u00e0 Casablanca\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,8,26,42,43,79,96,19],"tags":[],"class_list":["post-345","post","type-post","status-publish","format-standard","hentry","category-luc-legay","category-medias","category-blogs","category-workshop","category-communique","category-formation","category-journalisme","category-evenement","entry"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/posts\/345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/comments?post=345"}],"version-history":[{"count":18,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/posts\/345\/revisions"}],"predecessor-version":[{"id":362,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/posts\/345\/revisions\/362"}],"wp:attachment":[{"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/media?parent=345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/categories?post=345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ru3.com\/luc\/wp-json\/wp\/v2\/tags?post=345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}